{"id":61480,"date":"2022-05-09T00:00:00","date_gmt":"2022-05-08T22:00:00","guid":{"rendered":"https:\/\/2025.teleskopshop.ch\/shop\/senza-categoria\/barr-stroud-fernglas-series-4-ed-8x42\/"},"modified":"2025-01-25T13:24:58","modified_gmt":"2025-01-25T12:24:58","slug":"barr-stroud-fernglas-series-4-ed-8x42","status":"publish","type":"product","link":"https:\/\/www.teleskopshop.ch\/it\/shop\/ottica\/binocoli-e-occhiali-da-opera\/binocoli\/binocoli-barr-stroud\/barr-stroud-fernglas-series-4-ed-8x42\/","title":{"rendered":"Binocolo Barr &amp; Stroud Serie 4 ED 8&#215;42"},"content":{"rendered":"<p>Binocoli Serie 4 ED Questa serie Barr &amp; Stroud offre la massima qualit\u00e0 di binocoli molto precisi per osservazioni eccellenti. Vi vengono offerti un&#8217;alta risoluzione e una variet\u00e0 di contrasti con un&#8217;eccellente precisione del colore. &#8211; Ottica completamente multistrato &#8211; Impermeabile fino a una profondit\u00e0 di 1,5 m per circa 3 minuti &#8211; Riempimento di azoto, previene l&#8217;appannamento dell&#8217;umidit\u00e0 nell&#8217;ottica &#8211; Armatura in gomma resistente &#8211; Cappucci oculari rimovibili &#8211; Cappucci antipolvere &#8211; Prismi BaK-4 con rivestimento di fase &#8211; Conchiglie oculari in metallo rimovibili &#8211; Copertura antipioggia &#8211; Policarbonato leggero &#8211; custodia per il trasporto &#8211; tracolla &#8211; copriobiettivo Sorprendentemente, questo nuovo modello di binocolo Barr&amp;Stroud ricorda i suoi famosi predecessori Barr&amp;Stroud del passato. Questa \u00e8 una tendenza che torna al design del &#8220;ponte aperto&#8221;. Questi modelli presentano una serie di vantaggi rispetto al design tradizionalmente esistente. Il pi\u00f9 grande vantaggio \u00e8 la semplice maneggevolezza ergonomica e confortevole offerta da questo modello. Ultimo ma non meno importante, il peso ridotto del modello &#8220;Open Bridge&#8221; \u00e8 un chiaro vantaggio. Ci\u00f2 rende i modelli della Serie 4 particolarmente interessanti per escursionisti e camminatori. Tutti i modelli della Serie 4 includono copriobiettivi fissati, parapioggia, tracolla e custodia protettiva.<\/p>\n<p>Generale<\/p>\n<table>\n<tr>\n<td>Peso<\/td>\n<p> di spedizione <\/p>\n<td>1,1<\/td>\n<p> kg<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Dimensioni<\/td>\n<p> spedizione <\/p>\n<td>16x8x18,5 cm<\/td>\n<\/tr>\n<\/table>\n<p>Dati: Barr &amp; Stroud<\/p>\n<table>\n<tr>\n<td>Digitare<\/td>\n<td>bordo del tetto<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Ingrandimento<\/td>\n<td>8x<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Diametro lente obiettivo (mm)<\/td>\n<td>42<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Pupilla di uscita (mm)<\/td>\n<td>5,25<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Sistema di messa a fuoco<\/td>\n<td>centrale<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>Tipi di prismi di <\/p>\n<td>vetro<\/td>\n<td>BaK-4<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Twilight<\/td>\n<td>numero 18.33<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Intensit\u00e0<\/td>\n<p> luminosa <\/p>\n<td>27.56<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Rivestimento lenti<\/td>\n<td>FMC<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>Estrazione <\/p>\n<td>oculare all&#8217;oculare (mm)<\/td>\n<td>18,80<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Distanza interpupillare regolabile (mm)<\/td>\n<td>56-74<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>Campo <\/p>\n<td>visivo a 1000m<\/td>\n<td>114m<\/td>\n<\/tr>\n<\/table>\n<table>\n<tr>\n<td>Distanza minima di messa a fuoco (m)<\/td>\n<td>\n<table>\n<tr>\n<td>A prova di schizzi<\/td>\n<td>s\u00ec<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Binocolo Barr &amp; Stroud Serie 4 ED 8&#215;42<\/p>\n","protected":false},"featured_media":6239,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[684],"product_cat":[1346,1349,1343,1340],"product_tag":[],"class_list":{"0":"post-61480","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-barr-stroud","7":"product_cat-binocoli","8":"product_cat-binocoli-barr-stroud","9":"product_cat-binocoli-e-occhiali-da-opera","10":"product_cat-ottica","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product\/61480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/comments?post=61480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/media\/6239"}],"wp:attachment":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/media?parent=61480"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_brand?post=61480"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_cat?post=61480"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_tag?post=61480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}