{"id":59596,"date":"2023-12-18T00:00:00","date_gmt":"2023-12-17T23:00:00","guid":{"rendered":"https:\/\/2025.teleskopshop.ch\/shop\/senza-categoria\/baader-m72a-x-1-click-lock-klemme\/"},"modified":"2025-01-25T13:32:34","modified_gmt":"2025-01-25T12:32:34","slug":"baader-m72a-x-1-click-lock-klemme","status":"publish","type":"product","link":"https:\/\/www.teleskopshop.ch\/it\/shop\/ottica\/prolunghe-ottiche\/oculari\/baader-m72a-x-1-click-lock-klemme\/","title":{"rendered":"Baader M72a x 1 morsetto di bloccaggio a scatto"},"content":{"rendered":"<p>Morsetto Baader KlickLock da 2&#8243; per filettatura M72 per Takahashi grande<br \/>\nRifrattori #2956272.<br \/>\nAzionare la leva rotante del KlickLock senza alcuno sforzo<br \/>\nmeccanismo e bloccare un diagonale a stella da 2&#8243;, un oculare o<br \/>\nun adattatore da 2&#8243; esattamente sull&#8217;asse ottico. Il morsetto ClickLock<br \/>\ndistribuisce la pressione in modo uniforme sulla parete della custodia e la sollecita<br \/>\nquindi adattatore o oculare meno forte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morsetto Baader KlickLock da 2&#8243; per filettatura M72 per Takahashi grande Rifrattori #2956272. Azionare la leva rotante del KlickLock senza alcuno sforzo meccanismo e bloccare un diagonale a stella da 2&#8243;, un oculare o un adattatore da 2&#8243; esattamente sull&#8217;asse ottico. Il morsetto ClickLock distribuisce la pressione in modo uniforme sulla parete della custodia e [&hellip;]<\/p>\n","protected":false},"featured_media":9271,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[679],"product_cat":[1478,1340],"product_tag":[],"class_list":["post-59596","product","type-product","status-publish","has-post-thumbnail","product_brand-baader","product_cat-oculari","product_cat-ottica","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product\/59596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/comments?post=59596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/media\/9271"}],"wp:attachment":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/media?parent=59596"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_brand?post=59596"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_cat?post=59596"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_tag?post=59596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}