{"id":58432,"date":"2023-12-18T00:00:00","date_gmt":"2023-12-17T23:00:00","guid":{"rendered":"https:\/\/2025.teleskopshop.ch\/shop\/senza-categoria\/baader-m54-fein-abstimmring-set\/"},"modified":"2025-01-25T13:30:07","modified_gmt":"2025-01-25T12:30:07","slug":"baader-m54-fein-abstimmring-set","status":"publish","type":"product","link":"https:\/\/www.teleskopshop.ch\/it\/shop\/astronomia-accessori-it\/adattatori\/anelli-di-regolazione-fine\/baader-m54-fein-abstimmring-set\/","title":{"rendered":"Set di anelli di sintonia Baader M54"},"content":{"rendered":"<p>Anelli intermedi del sistema M54 (anelli di sintonia), disponibili nei punti di forza<br \/>\n0,3 mm (nero), 0,5 mm (rosso), 1 mm (oro).<br \/>\nAnelli di prolunga molto sottili per la messa a punto nel sistema M54<br \/>\nInserire anelli con diametro M54 senza filettatura.<br \/>\nSi adatta a qualsiasi connessione a vite M54, corrisponde a circa 2\/5<br \/>\n(0,3 mm), 2\/3 (0,5 mm) o 1 1\/3 (1 mm) di giro del filo. L&#8217;informazione<br \/>\nalla rotazione del filo pu\u00f2 variare leggermente.<br \/>\nImpedisce che un morsetto a vite M54 si blocchi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anelli intermedi del sistema M54 (anelli di sintonia), disponibili nei punti di forza 0,3 mm (nero), 0,5 mm (rosso), 1 mm (oro). Anelli di prolunga molto sottili per la messa a punto nel sistema M54 Inserire anelli con diametro M54 senza filettatura. Si adatta a qualsiasi connessione a vite M54, corrisponde a circa 2\/5 (0,3 [&hellip;]<\/p>\n","protected":false},"featured_media":9947,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[679],"product_cat":[1655,1658,1667],"product_tag":[],"class_list":{"0":"post-58432","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-baader","7":"product_cat-astronomia-accessori-it","8":"product_cat-adattatori","9":"product_cat-anelli-di-regolazione-fine","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product\/58432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/comments?post=58432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/media\/9947"}],"wp:attachment":[{"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/media?parent=58432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_brand?post=58432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_cat?post=58432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/it\/wp-json\/wp\/v2\/product_tag?post=58432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}