{"id":59783,"date":"2023-12-18T00:00:00","date_gmt":"2023-12-17T23:00:00","guid":{"rendered":"https:\/\/2025.teleskopshop.ch\/shop\/non%20class\u00e9\/baader-2a-t-2i-gewinde-reduzierring\/"},"modified":"2025-01-25T11:58:27","modified_gmt":"2025-01-25T10:58:27","slug":"baader-2a-t-2i-gewinde-reduzierring","status":"publish","type":"product","link":"https:\/\/www.teleskopshop.ch\/fr\/shop\/optique\/extensions-optiques\/oculaires\/baader-2a-t-2i-gewinde-reduzierring\/","title":{"rendered":"Baader 2&Prime;A\/T-2i Bague r\u00e9ductrice de filetage"},"content":{"rendered":"<p>Convertit n\u2019importe quel filetage femelle de 2 po (SC) en T-2 (M42 x 0,75)<br \/>\nFiletage int\u00e9rieur &#8211; sans allongement de la longueur optique&nbsp;;<br \/>\nFabriqu\u00e9 comme un adaptateur pour connecter l\u2019Hyperion Universal Zoom Mark IV \u00e0<br \/>\nde pouvoir adapter n\u2019importe quel fil photographique T-2, mais aussi de pouvoir<br \/>\npolyvalent et peut \u00eatre utilis\u00e9 de diverses autres mani\u00e8res&nbsp;;<br \/>\nConvient pour adapter n\u2019importe quel accessoire avec T-2 m\u00e2le<br \/>\nFiletage de raccordement (par ex. pour le raccordement \u00e0 notre VariLock 20-29 ou<br \/>\nBornes VariLock 29-46) ;<br \/>\nAdaptateur avec filetage continu 2&nbsp;\u00bb m\u00e2le et T-2 femelle ainsi que deux<br \/>\nPer\u00e7age de trous avant<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convertit n\u2019importe quel filetage femelle de 2 po (SC) en T-2 (M42 x 0,75) Filetage int\u00e9rieur &#8211; sans allongement de la longueur optique&nbsp;; Fabriqu\u00e9 comme un adaptateur pour connecter l\u2019Hyperion Universal Zoom Mark IV \u00e0 de pouvoir adapter n\u2019importe quel fil photographique T-2, mais aussi de pouvoir polyvalent et peut \u00eatre utilis\u00e9 de diverses autres [&hellip;]<\/p>\n","protected":false},"featured_media":10290,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[679],"product_cat":[1477,1339],"product_tag":[],"class_list":["post-59783","product","type-product","status-publish","has-post-thumbnail","product_brand-baader","product_cat-oculaires","product_cat-optique","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product\/59783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/comments?post=59783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/media\/10290"}],"wp:attachment":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/media?parent=59783"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=59783"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=59783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=59783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}