{"id":59352,"date":"2023-12-18T00:00:00","date_gmt":"2023-12-17T23:00:00","guid":{"rendered":"https:\/\/2025.teleskopshop.ch\/shop\/non%20class\u00e9\/baader-2-bbhs-clicklock-zenitspiegel\/"},"modified":"2025-01-25T11:52:17","modified_gmt":"2025-01-25T10:52:17","slug":"baader-2-bbhs-clicklock-zenitspiegel","status":"publish","type":"product","link":"https:\/\/www.teleskopshop.ch\/fr\/shop\/optique\/extensions-optiques\/oculaires\/baader-2-bbhs-clicklock-zenitspiegel\/","title":{"rendered":"Miroir diagonal Baader 2&Prime; BBHS ClickLock"},"content":{"rendered":"<p>&#8211; Diagonale en \u00e9toile 2&Prime; BBHS Sitall avec pince ClickLock 2&Prime; et noir<br \/>\n Logement<br \/>\n&#8211; Mat\u00e9riau du miroir Astro Sitall (vitroc\u00e9ramique avec z\u00e9ro<br \/>\n coefficient de dilatation), finition de surface 1\/10 lambda<br \/>\n&#8211; La plus grande r\u00e9flectivit\u00e9 sur la plus grande plage spectrale de 390<br \/>\n jusqu&rsquo;\u00e0 2000 nm<br \/>\n&#8211; BBHS = rev\u00eatement d&rsquo;argent dur \u00e0 large bande avec di\u00e9lectrique<br \/>\n frais de protection<br \/>\n&#8211; id\u00e9al pour l&rsquo;observation et la photographie avec la plus grande brillance, m\u00eame dans<br \/>\n spectre infrarouge<br \/>\n&#8211; Les preuves montrent que les offres d&rsquo;argent en rapport avec la<br \/>\n Sitall r\u00e9sistant \u00e0 la temp\u00e9rature la meilleure exp\u00e9rience visuelle absolue<br \/>\n absence totale de lumi\u00e8re parasite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Diagonale en \u00e9toile 2&Prime; BBHS Sitall avec pince ClickLock 2&Prime; et noir Logement &#8211; Mat\u00e9riau du miroir Astro Sitall (vitroc\u00e9ramique avec z\u00e9ro coefficient de dilatation), finition de surface 1\/10 lambda &#8211; La plus grande r\u00e9flectivit\u00e9 sur la plus grande plage spectrale de 390 jusqu&rsquo;\u00e0 2000 nm &#8211; BBHS = rev\u00eatement d&rsquo;argent dur \u00e0 large [&hellip;]<\/p>\n","protected":false},"featured_media":8458,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[679],"product_cat":[1477,1339],"product_tag":[],"class_list":["post-59352","product","type-product","status-publish","has-post-thumbnail","product_brand-baader","product_cat-oculaires","product_cat-optique","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product\/59352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/comments?post=59352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/media\/8458"}],"wp:attachment":[{"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/media?parent=59352"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=59352"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=59352"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teleskopshop.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=59352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}